{"id":9928,"date":"2026-07-09T10:40:15","date_gmt":"2026-07-09T10:40:15","guid":{"rendered":"https:\/\/arealorcaradio.es\/?p=9928"},"modified":"2026-07-09T10:40:15","modified_gmt":"2026-07-09T10:40:15","slug":"el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles","status":"publish","type":"post","link":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/","title":{"rendered":"El Auditorio Margarita Lozano cierra el a\u00f1o con una programaci\u00f3n de primer nivel que incluye \u00f3pera, teatro, m\u00fasica, humor y espect\u00e1culos infantiles"},"content":{"rendered":"<p><strong>\u00c1REA LORCA RADIO. Actualidad.<\/strong><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">9 de julio de 2026.\u00a0<\/span><\/b><span lang=\"es\">El concejal de Cultura del Ayuntamiento de Lorca, Santiago Parra, ha presentado este jueves la programaci\u00f3n cultural prevista para los meses de noviembre y diciembre en el Auditorio Margarita Lozano, una propuesta que reunir\u00e1 sobre el escenario a destacados nombres del panorama nacional y que incluir\u00e1 teatro, conciertos, humor, \u00f3pera, musicales y espect\u00e1culos dirigidos al p\u00fablico familiar.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-9931\" src=\"https:\/\/arealorcaradio.es\/wp-content\/uploads\/2026\/07\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-3-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/arealorcaradio.es\/wp-content\/uploads\/2026\/07\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-3-300x200.jpeg 300w, https:\/\/arealorcaradio.es\/wp-content\/uploads\/2026\/07\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-3-1024x683.jpeg 1024w, https:\/\/arealorcaradio.es\/wp-content\/uploads\/2026\/07\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-3-768x512.jpeg 768w, https:\/\/arealorcaradio.es\/wp-content\/uploads\/2026\/07\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-3-1536x1025.jpeg 1536w, https:\/\/arealorcaradio.es\/wp-content\/uploads\/2026\/07\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-3.jpeg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Santiago Parra ha destacado que \u00abel Auditorio Margarita Lozano contin\u00faa consolid\u00e1ndose como uno de los grandes espacios culturales y esc\u00e9nicos del sureste espa\u00f1ol, permiti\u00e9ndonos albergar espect\u00e1culos de primer nivel y seguir ampliando la oferta cultural del municipio\u00bb, y ha se\u00f1alado que \u00abdesde el Gobierno municipal seguimos trabajando para acercar a Lorca artistas y producciones de referencia nacional, de manera que los lorquinos puedan disfrutar de grandes conciertos y espect\u00e1culos sin necesidad de desplazarse a otras ciudades, al tiempo que reforzamos el atractivo cultural y tur\u00edstico de nuestro municipio, puesto que tambi\u00e9n son muchos los ciudadanos de otras provincias lim\u00edtrofes que nos visitan para asistir a estas representaciones culturales\u00bb.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">La programaci\u00f3n, cuyas entradas para asistir se pueden adquirir en la web\u00a0<a href=\"http:\/\/auditoriomargaritalozano.es\/\" target=\"_blank\" rel=\"noopener noreferrer\">auditoriomargaritalozano.es<\/a>, arrancar\u00e1 el viernes,\u00a0<b>6 de noviembre<\/b>, con la representaci\u00f3n de\u00a0<b>&#8216;Mejor no decirlo&#8217;<\/b>, protagonizada por Imanol Arias y Mar\u00eda Barranco, dirigida por Claudio Tolcachir y basada en un texto de Salom\u00e9 Lelouch. La funci\u00f3n comenzar\u00e1 a las 21 horas y las entradas tendr\u00e1n un precio de 24 y 22 euros. Un d\u00eda despu\u00e9s, el s\u00e1bado\u00a0<b>7 de noviembre<\/b>, el Auditorio acoger\u00e1 el concierto de\u00a0<b>Rev\u00f3lver<\/b>, que llegar\u00e1 a Lorca con su gira &#8216;La 03010 Tour&#8217;. La actuaci\u00f3n comenzar\u00e1 a las 21 horas y las entradas tendr\u00e1n un coste de 38 y 42 euros.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">La programaci\u00f3n continuar\u00e1 el mi\u00e9rcoles\u00a0<b>11 de noviembre<\/b>\u00a0con el espect\u00e1culo familiar\u00a0<b>&#8216;El patio de mi casa. Cantajuegos, el musical&#8217;<\/b>, recomendado para ni\u00f1os a partir de dos a\u00f1os. La funci\u00f3n, de 55 minutos de duraci\u00f3n, tendr\u00e1 lugar a las 18:30 horas y contar\u00e1 con entradas a un precio \u00fanico de 5 euros. El viernes\u00a0<b>13 de noviembre<\/b>\u00a0ser\u00e1 el turno de\u00a0<b>&#8216;Dulcinea&#8217;<\/b>, protagonizada por Paloma San Basilio junto al pianista Julio Awad, con direcci\u00f3n y dramaturgia de Juan Carlos Rubio. La representaci\u00f3n comenzar\u00e1 a las 21 horas y las entradas oscilar\u00e1n entre los 18 y los 22 euros.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">El humor llegar\u00e1 el domingo\u00a0<b>15 de noviembre<\/b>\u00a0de la mano del\u00a0<b>Comandante Lara<\/b>, que presentar\u00e1 su espect\u00e1culo &#8216;Los tres tenores&#8217; a partir de las 19 horas, con entradas de 24 y 26 euros. La \u00f3pera ocupar\u00e1 un lugar destacado el mi\u00e9rcoles\u00a0<b>18 de noviembre<\/b>\u00a0a las 20:30 horas con la representaci\u00f3n de\u00a0<b>&#8216;La flauta m\u00e1gica&#8217;<\/b>, de Mozart. La producci\u00f3n de \u00d3pera 2001 contar\u00e1 con solistas, orquesta y coro propios y podr\u00e1 disfrutarse en versi\u00f3n original alemana con traducci\u00f3n simult\u00e1nea al espa\u00f1ol. Las entradas tendr\u00e1n precios de 25 y 32 euros. El jueves\u00a0<b>26 de noviembre<\/b>\u00a0se ofrecer\u00e1 una\u00a0<b>versi\u00f3n familiar de &#8216;La flauta m\u00e1gica&#8217;<\/b>, recomendada para p\u00fablico a partir de siete a\u00f1os. La funci\u00f3n comenzar\u00e1 a las 18:30 horas y las entradas tendr\u00e1n un precio \u00fanico de 5 euros.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">La programaci\u00f3n de noviembre concluir\u00e1 el viernes\u00a0<b>27 de noviembre<\/b>\u00a0con la comedia\u00a0<b>&#8216;Baldosas&#8217;<\/b>, una divertida reflexi\u00f3n sobre el acceso a la vivienda protagonizada por Pedro Santomera, \u00c1ngela Pe\u00f1a, Manuel de Reyes y Elizabeth Sogorb. La representaci\u00f3n ser\u00e1 a las 21 horas y las entradas costar\u00e1n entre 8 y 10 euros.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">En\u00a0<b>diciembre<\/b>, la actividad arrancar\u00e1 el jueves 3 con el estreno del musical familiar\u00a0<b>&#8216;SuperZoe. En el planeta finito&#8217;<\/b>, escrito y dirigido por Juanchi Ruiz. La funci\u00f3n comenzar\u00e1 a las 18:30 horas y las entradas tendr\u00e1n precios de 10 y 12 euros. Adem\u00e1s, los d\u00edas 2 y 3 se realizar\u00e1n sesiones concertadas con centros educativos. La compa\u00f1\u00eda Yllana llegar\u00e1 el viernes\u00a0<b>11 de diciembre<\/b>\u00a0con\u00a0<b>&#8216;Maestrissimo&#8217;<\/b>, un espect\u00e1culo c\u00f3mico-musical para todos los p\u00fablicos que comenzar\u00e1 a las 20:30 horas. Las entradas tendr\u00e1n un coste de entre 12 y 15 euros.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">El s\u00e1bado\u00a0<b>12 de diciembre<\/b>\u00a0ser\u00e1 el turno del concierto de\u00a0<b>Santero y Los Muchachos<\/b>, que presentar\u00e1n en Lorca su gira &#8216;Todas las luces&#8217;. La actuaci\u00f3n comenzar\u00e1 a las 21 horas y las entradas tendr\u00e1n precios de 22 y 25 euros. La programaci\u00f3n continuar\u00e1 el mi\u00e9rcoles\u00a0<b>16 de diciembre<\/b>\u00a0con\u00a0<b>&#8216;La Bella Durmiente, el musical de tus recuerdos&#8217;<\/b>, una propuesta familiar de Trencad\u00eds Producciones que podr\u00e1 disfrutarse a las 18:30 horas, con entradas de 8 y 10 euros.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Por \u00faltimo, el martes\u00a0<b>22 de diciembre<\/b>, el Auditorio Margarita Lozano despedir\u00e1 la programaci\u00f3n de 2026 con\u00a0<b>&#8216;El show navide\u00f1o de la Pandilla de Drilo&#8217;<\/b>, una propuesta especialmente dise\u00f1ada para disfrutar en familia durante las fiestas navide\u00f1as. La funci\u00f3n comenzar\u00e1 a las 18:30 horas y las entradas tendr\u00e1n precios de 8 y 10 euros.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Junto a esta oferta cultural, el Ayuntamiento continuar\u00e1 desarrollando la campa\u00f1a municipal de teatro educativo\u00a0<b>&#8216;EducaEscena&#8217;<\/b>, que incluir\u00e1 el pr\u00f3ximo 3 de noviembre la representaci\u00f3n de &#8216;El rock se cuela en la escuela&#8217;, dirigida a escolares de entre 5 y 11 a\u00f1os, adem\u00e1s de avanzar a los centros educativos parte de la programaci\u00f3n prevista para el pr\u00f3ximo curso con el objetivo de facilitar la planificaci\u00f3n de la asistencia a las actividades.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Santiago Parra ha subrayado que \u00abhemos confeccionado una programaci\u00f3n equilibrada y pensada para todos los p\u00fablicos, combinando grandes nombres de la escena nacional con propuestas familiares y espect\u00e1culos de calidad que permiten que la cultura llegue a toda la poblaci\u00f3n\u00bb, y ha recordado, adem\u00e1s, que \u00abel Auditorio Margarita Lozano registra lleno tras lleno, convirti\u00e9ndose en un aut\u00e9ntico foco de atracci\u00f3n cultural no solo para los vecinos de Lorca, sino tambi\u00e9n para visitantes procedentes de toda la Regi\u00f3n de Murcia y de provincias lim\u00edtrofes\u00bb.<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">El concejal de Cultura ha concluido insistiendo en que \u00abqueremos seguir posicionando a Lorca como una ciudad din\u00e1mica, atractiva y llena de actividad durante todo el a\u00f1o, con una agenda de eventos repleta cada fin de semana. Creemos firmemente que la cultura es una de nuestras principales se\u00f1as de identidad y seguiremos apostando por una programaci\u00f3n ambiciosa y de calidad durante todo el a\u00f1o\u00bb.<\/span><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">La programaci\u00f3n del Auditorio Margarita Lozano, al detalle:<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><b><u><span lang=\"es\">Noviembre<\/span><\/u><\/b><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">Viernes, 6 de noviembre<\/span><\/b><span lang=\"es\">\u00a0| 21:00 h<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Teatro: &#8216;Mejor no decirlo&#8217;<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Imanol Arias y Mar\u00eda Barranco<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Entradas: 24 \u20ac \/ 22 \u20ac<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">S\u00e1bado, 7 de noviembre | 21:00 h<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Concierto: Rev\u00f3lver \u2013 &#8216;La 03010 Tour&#8217;<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Entradas: 42 \u20ac \/ 38 \u20ac<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00a0<\/span><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">Mi\u00e9rcoles, 11 de noviembre | 18:30 h<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Teatro musical familiar: &#8216;El patio de mi casa. Cantajuegos, el musical&#8217;<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">A partir de 2 a\u00f1os<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Entradas: 5 \u20ac<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00a0<\/span><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">Viernes, 13 de noviembre | 21:00 h<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Teatro musical: &#8216;Dulcinea&#8217;<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Con Paloma San Basilio y Julio Awad<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Entradas: 22 \u20ac \/ 18 \u20ac<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00a0<\/span><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">Domingo, 15 de noviembre | 19:00 h<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Humor: Comandante Lara \u2013 &#8216;Los tres tenores&#8217;<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Entradas: 26 \u20ac \/ 24 \u20ac<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00a0<\/span><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">Mi\u00e9rcoles, 18 de noviembre | 20:30 h<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00d3pera: &#8216;La flauta m\u00e1gica&#8217; (Mozart)<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00d3pera 2001<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Entradas: 32 \u20ac \/ 25 \u20ac<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00a0<\/span><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">Jueves, 26 de noviembre | 18:30 h<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00d3pera familiar: &#8216;La flauta m\u00e1gica&#8217;<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">A partir de 7 a\u00f1os<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Entradas: 5 \u20ac<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00a0<\/span><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">Viernes, 27 de noviembre | 21:00 h<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Comedia: &#8216;Baldosas&#8217;<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Entradas: 10 \u20ac \/ 8 \u20ac<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00a0<\/span><\/p>\n<p class=\"v1MsoNormal\"><b><u><span lang=\"es\">Diciembre<\/span><\/u><\/b><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">Jueves, 3 de diciembre | 18:30 h<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Estreno musical familiar: &#8216;SuperZoe. En el planeta finito&#8217;<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Entradas: 12 \u20ac \/ 10 \u20ac<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00a0<\/span><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">Viernes, 11 de diciembre | 20:30 h<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Espect\u00e1culo c\u00f3mico-musical: &#8216;Maestrissimo&#8217;<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Yllana<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Entradas: 15 \u20ac \/ 12 \u20ac<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00a0<\/span><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">S\u00e1bado, 12 de diciembre | 21:00 h<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Concierto: Santero y Los Muchachos \u2013 &#8216;Todas las luces&#8217;<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Entradas: 25 \u20ac \/ 22 \u20ac<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00a0<\/span><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">Mi\u00e9rcoles, 16 de diciembre | 18:30 h<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Musical familiar: &#8216;La Bella Durmiente, el musical de tus recuerdos&#8217;<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Entradas: 10 \u20ac \/ 8 \u20ac<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00a0<\/span><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">Martes, 22 de diciembre | 18:30 h<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Navidad en familia: &#8216;El show navide\u00f1o de la Pandilla de Drilo&#8217;<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Entradas: 10 \u20ac \/ 8 \u20ac<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">\u00a0<\/span><\/p>\n<p class=\"v1MsoNormal\"><b><u><span lang=\"es\">Campa\u00f1a municipal<\/span><\/u><\/b><u><span lang=\"es\">\u00a0<b>&#8216;EducaEscena&#8217;<\/b><\/span><\/u><\/p>\n<p class=\"v1MsoNormal\"><b><span lang=\"es\">Martes, 3 de noviembre<\/span><\/b><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">&#8216;El rock se cuela en la escuela&#8217;<\/span><\/p>\n<p class=\"v1MsoNormal\"><span lang=\"es\">Dirigido a escolares de entre 5 y 11 a\u00f1os.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c1REA LORCA RADIO. Actualidad. 9 de julio de 2026.\u00a0El concejal de Cultura del Ayuntamiento de Lorca, Santiago Parra, ha presentado este jueves la programaci\u00f3n cultural prevista para los meses de noviembre y diciembre en el Auditorio Margarita Lozano, una propuesta que reunir\u00e1 sobre el escenario a destacados nombres del panorama nacional y que incluir\u00e1 teatro, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":9929,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":15,"footnotes":""},"categories":[5,7],"tags":[],"class_list":["post-9928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad","category-lorca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Auditorio Margarita Lozano cierra el a\u00f1o con una programaci\u00f3n de primer nivel que incluye \u00f3pera, teatro, m\u00fasica, humor y espect\u00e1culos infantiles - AREA LORCA RADIO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Auditorio Margarita Lozano cierra el a\u00f1o con una programaci\u00f3n de primer nivel que incluye \u00f3pera, teatro, m\u00fasica, humor y espect\u00e1culos infantiles - AREA LORCA RADIO\" \/>\n<meta property=\"og:description\" content=\"\u00c1REA LORCA RADIO. Actualidad. 9 de julio de 2026.\u00a0El concejal de Cultura del Ayuntamiento de Lorca, Santiago Parra, ha presentado este jueves la programaci\u00f3n cultural prevista para los meses de noviembre y diciembre en el Auditorio Margarita Lozano, una propuesta que reunir\u00e1 sobre el escenario a destacados nombres del panorama nacional y que incluir\u00e1 teatro, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/\" \/>\n<meta property=\"og:site_name\" content=\"AREA LORCA RADIO\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-09T10:40:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/arealorcaradio.es\/wp-content\/uploads\/2026\/07\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Paco S\u00e1nchez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Paco S\u00e1nchez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/2026\\\/07\\\/09\\\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/2026\\\/07\\\/09\\\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\\\/\"},\"author\":{\"name\":\"Paco S\u00e1nchez\",\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/#\\\/schema\\\/person\\\/9fae605fc25b0f2c83c1ab207139bd27\"},\"headline\":\"El Auditorio Margarita Lozano cierra el a\u00f1o con una programaci\u00f3n de primer nivel que incluye \u00f3pera, teatro, m\u00fasica, humor y espect\u00e1culos infantiles\",\"datePublished\":\"2026-07-09T10:40:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/2026\\\/07\\\/09\\\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\\\/\"},\"wordCount\":1283,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/2026\\\/07\\\/09\\\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arealorcaradio.es\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-1.jpeg\",\"articleSection\":[\"ACTUALIDAD\",\"LORCA\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/2026\\\/07\\\/09\\\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/2026\\\/07\\\/09\\\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\\\/\",\"url\":\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/2026\\\/07\\\/09\\\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\\\/\",\"name\":\"El Auditorio Margarita Lozano cierra el a\u00f1o con una programaci\u00f3n de primer nivel que incluye \u00f3pera, teatro, m\u00fasica, humor y espect\u00e1culos infantiles - AREA LORCA RADIO\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/2026\\\/07\\\/09\\\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/2026\\\/07\\\/09\\\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/arealorcaradio.es\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-1.jpeg\",\"datePublished\":\"2026-07-09T10:40:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/#\\\/schema\\\/person\\\/9fae605fc25b0f2c83c1ab207139bd27\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/2026\\\/07\\\/09\\\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/2026\\\/07\\\/09\\\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/2026\\\/07\\\/09\\\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/arealorcaradio.es\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/arealorcaradio.es\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-1.jpeg\",\"width\":2048,\"height\":1366},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/2026\\\/07\\\/09\\\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/arealorcaradio.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Auditorio Margarita Lozano cierra el a\u00f1o con una programaci\u00f3n de primer nivel que incluye \u00f3pera, teatro, m\u00fasica, humor y espect\u00e1culos infantiles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/#website\",\"url\":\"https:\\\/\\\/arealorcaradio.es\\\/\",\"name\":\"AREA LORCA RADIO\",\"description\":\"Descubre la programaci\u00f3n actual en \u00c1rea Lorca Radio, tu fuente de entrenamiento y noticias locales. Sintoniza ahora y mantente conectado online.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arealorcaradio.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/arealorcaradio.es\\\/#\\\/schema\\\/person\\\/9fae605fc25b0f2c83c1ab207139bd27\",\"name\":\"Paco S\u00e1nchez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d67144e966420fb74aa84c9f2a0103be4724fd14db52b52d3b6bca749f257e79?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d67144e966420fb74aa84c9f2a0103be4724fd14db52b52d3b6bca749f257e79?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d67144e966420fb74aa84c9f2a0103be4724fd14db52b52d3b6bca749f257e79?s=96&d=mm&r=g\",\"caption\":\"Paco S\u00e1nchez\"},\"sameAs\":[\"https:\\\/\\\/arealorcaradio.es\"],\"url\":\"https:\\\/\\\/arealorcaradio.es\\\/index.php\\\/author\\\/admin_alorcaradio\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Auditorio Margarita Lozano cierra el a\u00f1o con una programaci\u00f3n de primer nivel que incluye \u00f3pera, teatro, m\u00fasica, humor y espect\u00e1culos infantiles - AREA LORCA RADIO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/","og_locale":"es_ES","og_type":"article","og_title":"El Auditorio Margarita Lozano cierra el a\u00f1o con una programaci\u00f3n de primer nivel que incluye \u00f3pera, teatro, m\u00fasica, humor y espect\u00e1culos infantiles - AREA LORCA RADIO","og_description":"\u00c1REA LORCA RADIO. Actualidad. 9 de julio de 2026.\u00a0El concejal de Cultura del Ayuntamiento de Lorca, Santiago Parra, ha presentado este jueves la programaci\u00f3n cultural prevista para los meses de noviembre y diciembre en el Auditorio Margarita Lozano, una propuesta que reunir\u00e1 sobre el escenario a destacados nombres del panorama nacional y que incluir\u00e1 teatro, [&hellip;]","og_url":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/","og_site_name":"AREA LORCA RADIO","article_published_time":"2026-07-09T10:40:15+00:00","og_image":[{"width":2048,"height":1366,"url":"https:\/\/arealorcaradio.es\/wp-content\/uploads\/2026\/07\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-1.jpeg","type":"image\/jpeg"}],"author":"Paco S\u00e1nchez","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Paco S\u00e1nchez","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/#article","isPartOf":{"@id":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/"},"author":{"name":"Paco S\u00e1nchez","@id":"https:\/\/arealorcaradio.es\/#\/schema\/person\/9fae605fc25b0f2c83c1ab207139bd27"},"headline":"El Auditorio Margarita Lozano cierra el a\u00f1o con una programaci\u00f3n de primer nivel que incluye \u00f3pera, teatro, m\u00fasica, humor y espect\u00e1culos infantiles","datePublished":"2026-07-09T10:40:15+00:00","mainEntityOfPage":{"@id":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/"},"wordCount":1283,"commentCount":0,"image":{"@id":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/#primaryimage"},"thumbnailUrl":"https:\/\/arealorcaradio.es\/wp-content\/uploads\/2026\/07\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-1.jpeg","articleSection":["ACTUALIDAD","LORCA"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/","url":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/","name":"El Auditorio Margarita Lozano cierra el a\u00f1o con una programaci\u00f3n de primer nivel que incluye \u00f3pera, teatro, m\u00fasica, humor y espect\u00e1culos infantiles - AREA LORCA RADIO","isPartOf":{"@id":"https:\/\/arealorcaradio.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/#primaryimage"},"image":{"@id":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/#primaryimage"},"thumbnailUrl":"https:\/\/arealorcaradio.es\/wp-content\/uploads\/2026\/07\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-1.jpeg","datePublished":"2026-07-09T10:40:15+00:00","author":{"@id":"https:\/\/arealorcaradio.es\/#\/schema\/person\/9fae605fc25b0f2c83c1ab207139bd27"},"breadcrumb":{"@id":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/#primaryimage","url":"https:\/\/arealorcaradio.es\/wp-content\/uploads\/2026\/07\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-1.jpeg","contentUrl":"https:\/\/arealorcaradio.es\/wp-content\/uploads\/2026\/07\/PROGRAMACION-AUDITORIO-NOVIEMBRE-DICIEMBRE-1.jpeg","width":2048,"height":1366},{"@type":"BreadcrumbList","@id":"https:\/\/arealorcaradio.es\/index.php\/2026\/07\/09\/el-auditorio-margarita-lozano-cierra-el-ano-con-una-programacion-de-primer-nivel-que-incluye-opera-teatro-musica-humor-y-espectaculos-infantiles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/arealorcaradio.es\/"},{"@type":"ListItem","position":2,"name":"El Auditorio Margarita Lozano cierra el a\u00f1o con una programaci\u00f3n de primer nivel que incluye \u00f3pera, teatro, m\u00fasica, humor y espect\u00e1culos infantiles"}]},{"@type":"WebSite","@id":"https:\/\/arealorcaradio.es\/#website","url":"https:\/\/arealorcaradio.es\/","name":"AREA LORCA RADIO","description":"Descubre la programaci\u00f3n actual en \u00c1rea Lorca Radio, tu fuente de entrenamiento y noticias locales. Sintoniza ahora y mantente conectado online.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arealorcaradio.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/arealorcaradio.es\/#\/schema\/person\/9fae605fc25b0f2c83c1ab207139bd27","name":"Paco S\u00e1nchez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d67144e966420fb74aa84c9f2a0103be4724fd14db52b52d3b6bca749f257e79?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d67144e966420fb74aa84c9f2a0103be4724fd14db52b52d3b6bca749f257e79?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d67144e966420fb74aa84c9f2a0103be4724fd14db52b52d3b6bca749f257e79?s=96&d=mm&r=g","caption":"Paco S\u00e1nchez"},"sameAs":["https:\/\/arealorcaradio.es"],"url":"https:\/\/arealorcaradio.es\/index.php\/author\/admin_alorcaradio\/"}]}},"_links":{"self":[{"href":"https:\/\/arealorcaradio.es\/index.php\/wp-json\/wp\/v2\/posts\/9928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arealorcaradio.es\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/arealorcaradio.es\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/arealorcaradio.es\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/arealorcaradio.es\/index.php\/wp-json\/wp\/v2\/comments?post=9928"}],"version-history":[{"count":2,"href":"https:\/\/arealorcaradio.es\/index.php\/wp-json\/wp\/v2\/posts\/9928\/revisions"}],"predecessor-version":[{"id":9932,"href":"https:\/\/arealorcaradio.es\/index.php\/wp-json\/wp\/v2\/posts\/9928\/revisions\/9932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/arealorcaradio.es\/index.php\/wp-json\/wp\/v2\/media\/9929"}],"wp:attachment":[{"href":"https:\/\/arealorcaradio.es\/index.php\/wp-json\/wp\/v2\/media?parent=9928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/arealorcaradio.es\/index.php\/wp-json\/wp\/v2\/categories?post=9928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/arealorcaradio.es\/index.php\/wp-json\/wp\/v2\/tags?post=9928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}